{"id":10009586,"date":"2025-05-12T13:52:32","date_gmt":"2025-05-12T18:52:32","guid":{"rendered":"https:\/\/www.centralhealth.net\/?post_type=tribe_events&#038;p=197358"},"modified":"2026-04-07T09:49:22","modified_gmt":"2026-04-07T14:49:22","slug":"free-zumba-classes-2","status":"publish","type":"tribe_events","link":"https:\/\/www.centralhealth.net\/fa\/event\/free-zumba-classes-2\/2027-02-16\/","title":{"rendered":"\u06a9\u0644\u0627\u0633\u200c\u0647\u0627\u06cc \u0631\u0627\u06cc\u06af\u0627\u0646 \u0632\u0648\u0645\u0628\u0627"},"content":{"rendered":"<p>\u0631\u0627\u06cc\u06af\u0627\u0646\u060c \u062f\u0648 \u0632\u0628\u0627\u0646\u0647 \u0648 \u0628\u0627\u0632 \u0628\u0631\u0627\u06cc \u062c\u0627\u0645\u0639\u0647<\/p>\n<p>\u0628\u0647 \u06a9\u0644\u0627\u0633\u06cc \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u0631\u0642\u0635 \u0648 \u062a\u0646\u0627\u0633\u0628 \u0627\u0646\u062f\u0627\u0645 \u0628\u067e\u06cc\u0648\u0646\u062f\u06cc\u062f \u06a9\u0647 \u0631\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0642\u0648\u06cc\u062a \u0648 \u0627\u0633\u062a\u062d\u06a9\u0627\u0645 \u0639\u0636\u0644\u0627\u062a\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc\u060c \u0628\u0647\u0628\u0648\u062f \u0648\u0636\u0639\u06cc\u062a \u0628\u062f\u0646 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0633\u062a\u0642\u0627\u0645\u062a \u06a9\u0644\u06cc \u062a\u0631\u06a9\u06cc\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3>\u0642\u0628\u0644 \u0627\u0632 \u0631\u0641\u062a\u0646 \u0628\u062f\u0627\u0646\u06cc\u062f<\/h3>\n<ul>\n<li>\u062f\u0647 \u062f\u0642\u06cc\u0642\u0647 \u0632\u0648\u062f\u062a\u0631 \u0628\u0631\u0627\u06cc \u062b\u0628\u062a \u0646\u0627\u0645 (\u0641\u0642\u0637 \u0628\u0631\u0627\u06cc \u0627\u0648\u0644\u06cc\u0646 \u0628\u0627\u0631) \u062d\u0627\u0636\u0631 \u0634\u0648\u06cc\u062f<\/li>\n<li>\u0641\u0636\u0627 \u0645\u062d\u062f\u0648\u062f \u0627\u0633\u062a<\/li>\n<li>\u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u06a9\u0648\u062f\u06a9 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u06cc\u0633\u062a<\/li>\n<li>\u0648\u0632\u0646\u0647\u200c\u0647\u0627\u06cc \u0633\u0628\u06a9 \u062f\u0633\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u062e\u0648\u0627\u0647\u062f \u0634\u062f<\/li>\n<\/ul>\n<p>\u0628\u0631\u0627\u06cc \u0633\u0648\u0627\u0644\u0627\u062a\u060c \u0628\u0627 \u0634\u0645\u0627\u0631\u0647 512.978.8570 \u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>","protected":false},"excerpt":{"rendered":"<p>Free, bilingual, and open to the community Join a dance and fitness-focused class that blends international rhythms to tone and strengthen muscles, enhance coordination, improve posture, and boost overall endurance. [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":204420,"template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[1370,1378],"class_list":["post-10009586","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","tribe_events_cat-del-valle-health-and-wellness","tribe_events_cat-wellness","cat_del-valle-health-and-wellness","cat_wellness","tribe-recurring-event","tribe-recurring-event-parent","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events\/10009586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/users\/59"}],"version-history":[{"count":0,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events\/10009586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/media\/204420"}],"wp:attachment":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/media?parent=10009586"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tags?post=10009586"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=10009586"}],"curies":[{"name":"\u0648\u0631\u062f\u067e\u0631\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}