{"id":10019312,"date":"2024-03-14T11:59:28","date_gmt":"2024-03-14T16:59:28","guid":{"rendered":"https:\/\/www.centralhealth.net\/?post_type=tribe_events&#038;p=184455"},"modified":"2025-12-03T09:45:03","modified_gmt":"2025-12-03T15:45:03","slug":"healthy-chef-cooking-class-english","status":"publish","type":"tribe_events","link":"https:\/\/www.centralhealth.net\/fa\/event\/healthy-chef-cooking-class-english\/2031-05-05\/","title":{"rendered":"\u06a9\u0644\u0627\u0633 \u0622\u0634\u067e\u0632\u06cc \u0633\u0631\u0622\u0634\u067e\u0632 \u0633\u0627\u0644\u0645 - \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc"},"content":{"rendered":"<p>\u0627\u06cc\u0646 \u06cc\u06a9 \u0628\u0631\u0646\u0627\u0645\u0647 \u0634\u0634 \u0647\u0641\u062a\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0633\u0644\u0627\u0645\u062a \u0634\u0645\u0627 \u0628\u0647 \u0634\u06cc\u0648\u0647\u200c\u0627\u06cc \u0633\u0631\u06af\u0631\u0645\u200c\u06a9\u0646\u0646\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u06a9\u0644\u0627\u0633\u200c\u0647\u0627 \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u062a\u063a\u0630\u06cc\u0647 \u062b\u0628\u062a\u200c\u0634\u062f\u0647 CommUnityCare \u0628\u0647 \u0632\u0628\u0627\u0646 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u062f\u0633\u062a\u0648\u0631 \u0627\u0644\u0639\u0645\u0644\u200c\u0647\u0627\u06cc \u0633\u0627\u0644\u0645 \u062c\u062f\u06cc\u062f \u0631\u0627 \u0628\u06cc\u0627\u0645\u0648\u0632\u06cc\u062f. \u0638\u0631\u0641\u06cc\u062a \u0645\u062d\u062f\u0648\u062f \u0627\u0633\u062a \u0648 \u0628\u0627\u06cc\u062f \u0642\u0628\u0644 \u0627\u0632 \u062f\u0648\u0631\u0647 \u0634\u0634 \u0647\u0641\u062a\u0647\u200c\u0627\u06cc \u0628\u0639\u062f\u06cc \u0628\u0627 \u0634\u0645\u0627\u0631\u0647 512.978.8528 \u062b\u0628\u062a \u0646\u0627\u0645 \u06a9\u0646\u06cc\u062f.<\/p>","protected":false},"excerpt":{"rendered":"<p>This is six week program to improve your health in a fun way. Learn new healthy recipes in these classes which are led by CommUnityCare\u2019s Registered Dietitians in English. Space [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[501,1378],"class_list":["post-10019312","tribe_events","type-tribe_events","status-publish","tribe_events_cat-southeast-health-wellness-center-schedule","tribe_events_cat-wellness","cat_southeast-health-wellness-center-schedule","cat_wellness","tribe-recurring-event","tribe-recurring-event-parent","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events\/10019312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/users\/59"}],"version-history":[{"count":0,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events\/10019312\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/media?parent=10019312"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tags?post=10019312"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.centralhealth.net\/fa\/wp-json\/wp\/v2\/tribe_events_cat?post=10019312"}],"curies":[{"name":"\u0648\u0631\u062f\u067e\u0631\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}