{"id":10009551,"date":"2025-05-12T13:52:32","date_gmt":"2025-05-12T18:52:32","guid":{"rendered":"https:\/\/www.centralhealth.net\/?post_type=tribe_events&#038;p=197358"},"modified":"2026-04-07T09:49:22","modified_gmt":"2026-04-07T14:49:22","slug":"free-zumba-classes-2","status":"publish","type":"tribe_events","link":"https:\/\/www.centralhealth.net\/ne\/event\/free-zumba-classes-2\/2026-10-15\/","title":{"rendered":"\u0928\u093f:\u0936\u0941\u0932\u094d\u0915 \u091c\u0941\u092e\u094d\u092c\u093e \u0915\u0915\u094d\u0937\u093e\u0939\u0930\u0942"},"content":{"rendered":"<p>\u0928\u093f\u0903\u0936\u0941\u0932\u094d\u0915, \u0926\u094d\u0935\u093f\u092d\u093e\u0937\u0940, \u0930 \u0938\u092e\u0941\u0926\u093e\u092f\u0915\u093e \u0932\u093e\u0917\u093f \u0916\u0941\u0932\u093e<\/p>\n<p>\u092e\u093e\u0902\u0938.<\/p>\n<h3>\u091c\u093e\u0928\u094d<\/h3>\n<ul>\n<li>\u0926\u0930\u094d\u0924\u093e \u0917\u0930\u094d\u0928\u0915\u093e \u0932\u093e\u0917\u093f \u0967\u0966 \u092e\u093f\u0928\u0947\u091f \u092a\u0939\u093f\u0932\u0947 \u0906\u0907\u092a\u0941\u0917\u094d\u0928\u0941\u0939\u094b\u0938\u094d (\u092a\u0939\u093f\u0932\u094b \u092a\u091f\u0915 \u092e\u093e\u0924\u094d\u0930)<\/li>\n<li>\u0920\u093e\u0909\u0901 \u0938\u0940\u092e\u093f\u0924 \u091b<\/li>\n<li>\u092c\u093e\u0932 \u0939\u0947\u0930\u091a\u093e\u0939 \u0909\u092a\u0932\u092c\u094d\u0927 \u091b\u0948\u0928<\/li>\n<li>\u0939\u0932\u094d\u0915\u093e \u0924\u094c\u0932\u0915\u093e<\/li>\n<\/ul>\n<p>\u092a\u094d\u0930\u0936\u094d\u0928\u0939\u0930\u0942\u0915\u093e \u0932\u093e\u0917\u093f, \u096b\u0967\u0968.\u096f\u096d\u096e.\u096e\u096b\u096d\u0966 \u092e\u093e \u092b\u094b\u0928 \u0917\u0930\u094d\u0928\u0941\u0939\u094b\u0938\u094d\u0964<\/p>","protected":false},"excerpt":{"rendered":"<p>Free, bilingual, and open to the community Join a dance and fitness-focused class that blends international rhythms to tone and strengthen muscles, enhance coordination, improve posture, and boost overall endurance. [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":204420,"template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[1370,1378],"class_list":["post-10009551","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","tribe_events_cat-del-valle-health-and-wellness","tribe_events_cat-wellness","cat_del-valle-health-and-wellness","cat_wellness","tribe-recurring-event","tribe-recurring-event-parent","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/tribe_events\/10009551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/users\/59"}],"version-history":[{"count":0,"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/tribe_events\/10009551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/media\/204420"}],"wp:attachment":[{"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/media?parent=10009551"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/tags?post=10009551"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.centralhealth.net\/ne\/wp-json\/wp\/v2\/tribe_events_cat?post=10009551"}],"curies":[{"name":"\u0921\u092c\u094d\u0932\u094d\u092f\u0942\u092a\u0940","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}