{"id":10019309,"date":"2024-03-14T11:59:28","date_gmt":"2024-03-14T16:59:28","guid":{"rendered":"https:\/\/www.centralhealth.net\/?post_type=tribe_events&#038;p=184455"},"modified":"2025-12-03T09:45:03","modified_gmt":"2025-12-03T15:45:03","slug":"healthy-chef-cooking-class-english","status":"publish","type":"tribe_events","link":"https:\/\/www.centralhealth.net\/vi\/event\/healthy-chef-cooking-class-english\/2031-04-14\/","title":{"rendered":"L\u1edbp h\u1ecdc n\u1ea5u \u0103n Healthy Chef \u2013 Ti\u1ebfng Anh"},"content":{"rendered":"<p>\u0110\u00e2y l\u00e0 ch\u01b0\u01a1ng tr\u00ecnh k\u00e9o d\u00e0i s\u00e1u tu\u1ea7n nh\u1eb1m c\u1ea3i thi\u1ec7n s\u1ee9c kh\u1ecfe c\u1ee7a b\u1ea1n m\u1ed9t c\u00e1ch th\u00fa v\u1ecb. Trong c\u00e1c l\u1edbp h\u1ecdc n\u00e0y, b\u1ea1n s\u1ebd h\u1ecdc c\u00e1c c\u00f4ng th\u1ee9c n\u1ea5u \u0103n l\u00e0nh m\u1ea1nh m\u1edbi do c\u00e1c Chuy\u00ean gia Dinh d\u01b0\u1ee1ng \u0110\u0103ng k\u00fd c\u1ee7a CommUnityCare h\u01b0\u1edbng d\u1eabn b\u1eb1ng ti\u1ebfng Anh. S\u1ed1 l\u01b0\u1ee3ng ch\u1ed7 ng\u1ed3i c\u00f3 h\u1ea1n v\u00e0 b\u1ea1n ph\u1ea3i \u0111\u0103ng k\u00fd tr\u01b0\u1edbc qua s\u1ed1 \u0111i\u1ec7n tho\u1ea1i 512.978.8528 tr\u01b0\u1edbc khi kh\u00f3a h\u1ecdc s\u00e1u tu\u1ea7n ti\u1ebfp theo b\u1eaft \u0111\u1ea7u.<\/p>","protected":false},"excerpt":{"rendered":"<p>This is six week program to improve your health in a fun way. Learn new healthy recipes in these classes which are led by CommUnityCare\u2019s Registered Dietitians in English. Space [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[501,1378],"class_list":["post-10019309","tribe_events","type-tribe_events","status-publish","tribe_events_cat-southeast-health-wellness-center-schedule","tribe_events_cat-wellness","cat_southeast-health-wellness-center-schedule","cat_wellness","tribe-recurring-event","tribe-recurring-event-parent","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/tribe_events\/10019309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/users\/59"}],"version-history":[{"count":0,"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/tribe_events\/10019309\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/media?parent=10019309"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/tags?post=10019309"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.centralhealth.net\/vi\/wp-json\/wp\/v2\/tribe_events_cat?post=10019309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}